{"id":9257,"date":"2020-08-12T16:40:35","date_gmt":"2020-08-12T22:40:35","guid":{"rendered":"http:\/\/elinformativotam.com\/?p=9257"},"modified":"2020-08-12T16:40:35","modified_gmt":"2020-08-12T22:40:35","slug":"el-progreso-de-tampico-no-se-detiene-chucho-nader","status":"publish","type":"post","link":"https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/","title":{"rendered":"EL PROGRESO DE TAMPICO NO SE DETIENE: CHUCHO NADER"},"content":{"rendered":"<h2><em><strong>*Inicia Nueva Obra De Pavimentaci\u00f3n En La Colonia Obrera<\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>El Presidente Municipal Chucho Nader, acompa\u00f1ado de su esposa, A\u00edda F\u00e9res de Nader, Presidenta del Sistema DIF Tampico puso en marcha la pavimentaci\u00f3n a base de concreto hidr\u00e1ulico en la calle Leona Vicario, entre Nayarit y Lerdo de Tejada de la colonia Obrera, donde se destinar\u00e1 una inversi\u00f3n cercana a un mill\u00f3n 700 mil pesos.<\/p>\n<p>&nbsp;<\/p>\n<p>El Alcalde destac\u00f3 que el mejoramiento vial de la ciudad, adem\u00e1s de generar bienestar y seguridad a las familias, contribuye a la promoci\u00f3n municipal y a la atracci\u00f3n de nuevas inversiones, por lo que, asegur\u00f3 que se continuar\u00e1 reduciendo el rezago que existe en este rubro.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Durante la presente administraci\u00f3n, hemos modernizado cientos de vialidades en los diferentes sectores de la ciudad, cumpliendo nuestro compromiso de construir un municipio moderno, con mejor calidad de vida y mayores oportunidades de desarrollo para todos; una ciudad que destaque a nivel nacional&#8221;, mencion\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante el banderazo de inicio al que asistieron tambi\u00e9n, el Secretario de Bienestar Social y Deportes, Ren\u00e9 Sent\u00edes Barrios y el titular de Obras P\u00fablicas, Pedro Pablo Rangel Cerrillo, el jefe de la comuna se\u00f1al\u00f3 que en la colonia Obrera se han realizado diversas obras de pavimentaci\u00f3n que le han dado al sector mayor conectividad y adelant\u00f3 que para el presente a\u00f1o se tiene programada la modernizaci\u00f3n de nuevas vialidades.<\/p>\n<p>&nbsp;<\/p>\n<p>Asegur\u00f3 que mediante un estrat\u00e9gico programa de obra p\u00fablica, se atienden las necesidades viales en los sectores m\u00e1s antiguos de la ciudad y reiter\u00f3 su compromiso de continuar impulsando el desarrollo urbano para garantizar mayor bienestar a las familias tampique\u00f1as.<\/p>\n<p>&nbsp;<\/p>\n<p>Explic\u00f3 que en la obra se llevar\u00e1 a cabo la reposici\u00f3n integral de las redes hidrosanitarias; construcci\u00f3n de guarniciones y banquetas; instalaci\u00f3n de nuevas luminarias y la colocaci\u00f3n de concreto hidr\u00e1ulico en una superficie de m\u00e1s de 682 metros cuadrados.<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte, Elena Berenice Medell\u00edn a nombre de los vecinos beneficiados, agradeci\u00f3 el inicio de la obra y subray\u00f3 que durante d\u00e9cadas la vialidad permaneci\u00f3 en el abandono.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Le agradecemos infinitamente la realizaci\u00f3n de esta obra, que por a\u00f1os fue olvidada por anteriores administraciones y que hoy, gracias a su trabajo comprometido en favor de los tampique\u00f1os, nos brindar\u00e1 mayor seguridad, mejor calidad de vida para nuestras familias y mayor plusval\u00eda a nuestras propiedades&#8221;, dijo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Inicia Nueva Obra De Pavimentaci\u00f3n En La Colonia Obrera &nbsp; El Presidente Municipal Chucho Nader, acompa\u00f1ado de su esposa, A\u00edda&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9257","post","type-post","status-publish","format-standard","hentry","category-tampico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EL PROGRESO DE TAMPICO NO SE DETIENE: CHUCHO NADER - EL INFORMATIVO DE TAMAULIPAS<\/title>\n<meta name=\"description\" content=\"*Inicia Nueva Obra De Pavimentaci\u00f3n En La Colonia Obrera &nbsp; El Presidente Municipal Chucho Nader, acompa\u00f1ado de su esposa, A\u00edda F\u00e9res de Nader,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EL PROGRESO DE TAMPICO NO SE DETIENE: CHUCHO NADER - EL INFORMATIVO DE TAMAULIPAS\" \/>\n<meta property=\"og:description\" content=\"*Inicia Nueva Obra De Pavimentaci\u00f3n En La Colonia Obrera &nbsp; El Presidente Municipal Chucho Nader, acompa\u00f1ado de su esposa, A\u00edda F\u00e9res de Nader,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/\" \/>\n<meta property=\"og:site_name\" content=\"EL INFORMATIVO DE TAMAULIPAS\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-12T22:40:35+00:00\" \/>\n<meta name=\"author\" content=\"El Informativo Tam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Informativo Tam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/08\\\/12\\\/el-progreso-de-tampico-no-se-detiene-chucho-nader\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/08\\\/12\\\/el-progreso-de-tampico-no-se-detiene-chucho-nader\\\/\"},\"author\":{\"name\":\"El Informativo Tam\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#\\\/schema\\\/person\\\/78e08040eed0f6110f0c5f83b6153590\"},\"headline\":\"EL PROGRESO DE TAMPICO NO SE DETIENE: CHUCHO NADER\",\"datePublished\":\"2020-08-12T22:40:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/08\\\/12\\\/el-progreso-de-tampico-no-se-detiene-chucho-nader\\\/\"},\"wordCount\":430,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#organization\"},\"articleSection\":[\"Tampico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/08\\\/12\\\/el-progreso-de-tampico-no-se-detiene-chucho-nader\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/08\\\/12\\\/el-progreso-de-tampico-no-se-detiene-chucho-nader\\\/\",\"url\":\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/08\\\/12\\\/el-progreso-de-tampico-no-se-detiene-chucho-nader\\\/\",\"name\":\"EL PROGRESO DE TAMPICO NO SE DETIENE: CHUCHO NADER - EL INFORMATIVO DE TAMAULIPAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#website\"},\"datePublished\":\"2020-08-12T22:40:35+00:00\",\"description\":\"*Inicia Nueva Obra De Pavimentaci\u00f3n En La Colonia Obrera &nbsp; El Presidente Municipal Chucho Nader, acompa\u00f1ado de su esposa, A\u00edda F\u00e9res de Nader,\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/08\\\/12\\\/el-progreso-de-tampico-no-se-detiene-chucho-nader\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#website\",\"url\":\"https:\\\/\\\/elinformativotam.com\\\/\",\"name\":\"EL INFORMATIVO DE TAMAULIPAS\",\"description\":\"Desde la Zona Metropolitana Para Todo M\u00e9xico\",\"publisher\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elinformativotam.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#organization\",\"name\":\"EL INFORMATIVO DE TAMAULIPAS\",\"url\":\"https:\\\/\\\/elinformativotam.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elinformativotam.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Cabezal.png\",\"contentUrl\":\"https:\\\/\\\/elinformativotam.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Cabezal.png\",\"width\":960,\"height\":640,\"caption\":\"EL INFORMATIVO DE TAMAULIPAS\"},\"image\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#\\\/schema\\\/person\\\/78e08040eed0f6110f0c5f83b6153590\",\"name\":\"El Informativo Tam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g\",\"caption\":\"El Informativo Tam\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL PROGRESO DE TAMPICO NO SE DETIENE: CHUCHO NADER - EL INFORMATIVO DE TAMAULIPAS","description":"*Inicia Nueva Obra De Pavimentaci\u00f3n En La Colonia Obrera &nbsp; El Presidente Municipal Chucho Nader, acompa\u00f1ado de su esposa, A\u00edda F\u00e9res de Nader,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/","og_locale":"es_MX","og_type":"article","og_title":"EL PROGRESO DE TAMPICO NO SE DETIENE: CHUCHO NADER - EL INFORMATIVO DE TAMAULIPAS","og_description":"*Inicia Nueva Obra De Pavimentaci\u00f3n En La Colonia Obrera &nbsp; El Presidente Municipal Chucho Nader, acompa\u00f1ado de su esposa, A\u00edda F\u00e9res de Nader,","og_url":"https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/","og_site_name":"EL INFORMATIVO DE TAMAULIPAS","article_published_time":"2020-08-12T22:40:35+00:00","author":"El Informativo Tam","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El Informativo Tam","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/#article","isPartOf":{"@id":"https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/"},"author":{"name":"El Informativo Tam","@id":"https:\/\/elinformativotam.com\/#\/schema\/person\/78e08040eed0f6110f0c5f83b6153590"},"headline":"EL PROGRESO DE TAMPICO NO SE DETIENE: CHUCHO NADER","datePublished":"2020-08-12T22:40:35+00:00","mainEntityOfPage":{"@id":"https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/"},"wordCount":430,"commentCount":0,"publisher":{"@id":"https:\/\/elinformativotam.com\/#organization"},"articleSection":["Tampico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/","url":"https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/","name":"EL PROGRESO DE TAMPICO NO SE DETIENE: CHUCHO NADER - EL INFORMATIVO DE TAMAULIPAS","isPartOf":{"@id":"https:\/\/elinformativotam.com\/#website"},"datePublished":"2020-08-12T22:40:35+00:00","description":"*Inicia Nueva Obra De Pavimentaci\u00f3n En La Colonia Obrera &nbsp; El Presidente Municipal Chucho Nader, acompa\u00f1ado de su esposa, A\u00edda F\u00e9res de Nader,","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elinformativotam.com\/index.php\/2020\/08\/12\/el-progreso-de-tampico-no-se-detiene-chucho-nader\/"]}]},{"@type":"WebSite","@id":"https:\/\/elinformativotam.com\/#website","url":"https:\/\/elinformativotam.com\/","name":"EL INFORMATIVO DE TAMAULIPAS","description":"Desde la Zona Metropolitana Para Todo M\u00e9xico","publisher":{"@id":"https:\/\/elinformativotam.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elinformativotam.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elinformativotam.com\/#organization","name":"EL INFORMATIVO DE TAMAULIPAS","url":"https:\/\/elinformativotam.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elinformativotam.com\/#\/schema\/logo\/image\/","url":"https:\/\/elinformativotam.com\/wp-content\/uploads\/2026\/02\/Cabezal.png","contentUrl":"https:\/\/elinformativotam.com\/wp-content\/uploads\/2026\/02\/Cabezal.png","width":960,"height":640,"caption":"EL INFORMATIVO DE TAMAULIPAS"},"image":{"@id":"https:\/\/elinformativotam.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elinformativotam.com\/#\/schema\/person\/78e08040eed0f6110f0c5f83b6153590","name":"El Informativo Tam","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g","caption":"El Informativo Tam"}}]}},"_links":{"self":[{"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/posts\/9257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/comments?post=9257"}],"version-history":[{"count":1,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/posts\/9257\/revisions"}],"predecessor-version":[{"id":9259,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/posts\/9257\/revisions\/9259"}],"wp:attachment":[{"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/media?parent=9257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/categories?post=9257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/tags?post=9257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}