{"id":10101,"date":"2020-09-07T07:39:43","date_gmt":"2020-09-07T13:39:43","guid":{"rendered":"http:\/\/elinformativotam.com\/?p=10101"},"modified":"2020-09-07T07:39:43","modified_gmt":"2020-09-07T13:39:43","slug":"lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero","status":"publish","type":"post","link":"https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/","title":{"rendered":"LLEVA MON MAR\u00d3N ALIMENTOS A LOS \u201cH\u00c9ROES DE LA SALUD\u201d DE HOSPITALES CANSECO , ISSSTE Y CIVIL DE MADERO"},"content":{"rendered":"<p>Ante la importancia que representan los m\u00e9dicos y personal sanitario en los diferentes hospitales p\u00fablicos de la zona sur de Tamaulipas para enfrentar a la pandemia provocada por el COVID 19, el Diputado Local por la zona norte de Tampico Mon Mar\u00f3n realizo una jornada de entrega de alimentos en los hospitales Carlos Canseco , ISSSTE y\u00a0 Civil de Ciudad Madero.<\/p>\n<p>&nbsp;<\/p>\n<p>El legislador local expres\u00f3 que\u00a0 los m\u00e9dicos, enfermeras y personal de salud est\u00e1n en la primera l\u00ednea de fuego, como son\u00a0 en\u00a0 las \u00e1reas \u201cCOVID 19\u201d de\u00a0 esos nosocomios p\u00fablicos, realizando jornadas largas de trabajo entregando su capacidad y esfuerzo para atender a los enfermos de coronavirus en el sur de Tamaulipas.<\/p>\n<p>&nbsp;<\/p>\n<p>Reitero que en\u00a0 muchas ocasiones, ante la imposibilidad de estar entrando y saliendo de estas \u00e1reas especiales y para\u00a0 reducir el riesgo de contagio\u00a0 , omiten salir a comer\u00a0 , por ello la importancia de\u00a0 esta acci\u00f3n de ayuda solidaria , con la entrega de alimentos para \u201clos h\u00e9roes de la salud\u201ddirectamente a sus zonas de trabajo.<\/p>\n<p>&nbsp;<\/p>\n<p>A pesar de las inclemencias del tiempo, al presentarse constantes lluvias en Tampico y Madero , la ma\u00f1ana del s\u00e1bado ,\u00a0 no fue impedimento para que el representante popular y su equipo de trabajo realizaran esta jornada solidaria a los profesionales de la salud en los hospitales Canseco , ISSSTE y Civil de Madero , refrendando su vocaci\u00f3n de trabajo y compromiso para coadyuvar a enfrentar al coronavirus y hacer frente com\u00fan para reducir los casos de contagio , como lo viene haciendo d\u00eda a d\u00eda el Gobierno de Tamaulipas que encabeza Francisco Garc\u00eda Cabeza de Vaca.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cLos h\u00e9roes de la salud , son sin lugar a dudas , quienes enfrentan cara a cara al COVID 19 , desde las \u00e1reas confinadas , atienden a\u00a0 las personas enfermas , dan su mayor esfuerzo e incluso arriesgan su vida , para salvar muchas , por ello es importante darles el apoyo con alimentaci\u00f3n en sus zonas de trabajo , para que no omitan sus comidas , pues est\u00e1n en la l\u00ednea de fuego , les hago patente mi reconocimiento por su ejemplar labor y les reitero mis acciones solidarias\u201d dijo el Diputado Mon Mar\u00f3n en las instalaciones del Hospital Canseco de Tampico.<\/p>\n<p>&nbsp;<\/p>\n<p>Finalmente, invito a la poblaci\u00f3n a continuar con las medidas de higiene personal , como es el constante lavado de manos , el uso del cubrebocas adem\u00e1s del distanciamiento social y en las medidas de sus posibilidades reducir la movilidad y qued\u00e1ndose el mayor tiempo en casa , pues con estas acciones efectivas de la poblaci\u00f3n , ayudaran al personal m\u00e9dico a que no tengan exceso de trabajo con m\u00e1s contagios e saturaci\u00f3n de hospitales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante la importancia que representan los m\u00e9dicos y personal sanitario en los diferentes hospitales p\u00fablicos de la zona sur de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10101","post","type-post","status-publish","format-standard","hentry","category-tampico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LLEVA MON MAR\u00d3N ALIMENTOS A LOS \u201cH\u00c9ROES DE LA SALUD\u201d DE HOSPITALES CANSECO , ISSSTE Y CIVIL DE MADERO - EL INFORMATIVO DE TAMAULIPAS<\/title>\n<meta name=\"description\" content=\"Ante la importancia que representan los m\u00e9dicos y personal sanitario en los diferentes hospitales p\u00fablicos de la zona sur de Tamaulipas para enfrentar a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LLEVA MON MAR\u00d3N ALIMENTOS A LOS \u201cH\u00c9ROES DE LA SALUD\u201d DE HOSPITALES CANSECO , ISSSTE Y CIVIL DE MADERO - EL INFORMATIVO DE TAMAULIPAS\" \/>\n<meta property=\"og:description\" content=\"Ante la importancia que representan los m\u00e9dicos y personal sanitario en los diferentes hospitales p\u00fablicos de la zona sur de Tamaulipas para enfrentar a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/\" \/>\n<meta property=\"og:site_name\" content=\"EL INFORMATIVO DE TAMAULIPAS\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-07T13:39:43+00:00\" \/>\n<meta name=\"author\" content=\"El Informativo Tam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Informativo Tam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/09\\\/07\\\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/09\\\/07\\\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\\\/\"},\"author\":{\"name\":\"El Informativo Tam\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#\\\/schema\\\/person\\\/78e08040eed0f6110f0c5f83b6153590\"},\"headline\":\"LLEVA MON MAR\u00d3N ALIMENTOS A LOS \u201cH\u00c9ROES DE LA SALUD\u201d DE HOSPITALES CANSECO , ISSSTE Y CIVIL DE MADERO\",\"datePublished\":\"2020-09-07T13:39:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/09\\\/07\\\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\\\/\"},\"wordCount\":474,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#organization\"},\"articleSection\":[\"Tampico\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/09\\\/07\\\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/09\\\/07\\\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\\\/\",\"url\":\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/09\\\/07\\\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\\\/\",\"name\":\"LLEVA MON MAR\u00d3N ALIMENTOS A LOS \u201cH\u00c9ROES DE LA SALUD\u201d DE HOSPITALES CANSECO , ISSSTE Y CIVIL DE MADERO - EL INFORMATIVO DE TAMAULIPAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#website\"},\"datePublished\":\"2020-09-07T13:39:43+00:00\",\"description\":\"Ante la importancia que representan los m\u00e9dicos y personal sanitario en los diferentes hospitales p\u00fablicos de la zona sur de Tamaulipas para enfrentar a\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elinformativotam.com\\\/index.php\\\/2020\\\/09\\\/07\\\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#website\",\"url\":\"https:\\\/\\\/elinformativotam.com\\\/\",\"name\":\"EL INFORMATIVO DE TAMAULIPAS\",\"description\":\"Desde la Zona Metropolitana Para Todo M\u00e9xico\",\"publisher\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elinformativotam.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#organization\",\"name\":\"EL INFORMATIVO DE TAMAULIPAS\",\"url\":\"https:\\\/\\\/elinformativotam.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elinformativotam.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Cabezal.png\",\"contentUrl\":\"https:\\\/\\\/elinformativotam.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Cabezal.png\",\"width\":960,\"height\":640,\"caption\":\"EL INFORMATIVO DE TAMAULIPAS\"},\"image\":{\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elinformativotam.com\\\/#\\\/schema\\\/person\\\/78e08040eed0f6110f0c5f83b6153590\",\"name\":\"El Informativo Tam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g\",\"caption\":\"El Informativo Tam\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LLEVA MON MAR\u00d3N ALIMENTOS A LOS \u201cH\u00c9ROES DE LA SALUD\u201d DE HOSPITALES CANSECO , ISSSTE Y CIVIL DE MADERO - EL INFORMATIVO DE TAMAULIPAS","description":"Ante la importancia que representan los m\u00e9dicos y personal sanitario en los diferentes hospitales p\u00fablicos de la zona sur de Tamaulipas para enfrentar a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/","og_locale":"es_MX","og_type":"article","og_title":"LLEVA MON MAR\u00d3N ALIMENTOS A LOS \u201cH\u00c9ROES DE LA SALUD\u201d DE HOSPITALES CANSECO , ISSSTE Y CIVIL DE MADERO - EL INFORMATIVO DE TAMAULIPAS","og_description":"Ante la importancia que representan los m\u00e9dicos y personal sanitario en los diferentes hospitales p\u00fablicos de la zona sur de Tamaulipas para enfrentar a","og_url":"https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/","og_site_name":"EL INFORMATIVO DE TAMAULIPAS","article_published_time":"2020-09-07T13:39:43+00:00","author":"El Informativo Tam","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"El Informativo Tam","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/#article","isPartOf":{"@id":"https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/"},"author":{"name":"El Informativo Tam","@id":"https:\/\/elinformativotam.com\/#\/schema\/person\/78e08040eed0f6110f0c5f83b6153590"},"headline":"LLEVA MON MAR\u00d3N ALIMENTOS A LOS \u201cH\u00c9ROES DE LA SALUD\u201d DE HOSPITALES CANSECO , ISSSTE Y CIVIL DE MADERO","datePublished":"2020-09-07T13:39:43+00:00","mainEntityOfPage":{"@id":"https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/"},"wordCount":474,"commentCount":0,"publisher":{"@id":"https:\/\/elinformativotam.com\/#organization"},"articleSection":["Tampico"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/","url":"https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/","name":"LLEVA MON MAR\u00d3N ALIMENTOS A LOS \u201cH\u00c9ROES DE LA SALUD\u201d DE HOSPITALES CANSECO , ISSSTE Y CIVIL DE MADERO - EL INFORMATIVO DE TAMAULIPAS","isPartOf":{"@id":"https:\/\/elinformativotam.com\/#website"},"datePublished":"2020-09-07T13:39:43+00:00","description":"Ante la importancia que representan los m\u00e9dicos y personal sanitario en los diferentes hospitales p\u00fablicos de la zona sur de Tamaulipas para enfrentar a","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elinformativotam.com\/index.php\/2020\/09\/07\/lleva-mon-maron-alimentos-a-los-heroes-de-la-salud-de-hospitales-canseco-issste-y-civil-de-madero\/"]}]},{"@type":"WebSite","@id":"https:\/\/elinformativotam.com\/#website","url":"https:\/\/elinformativotam.com\/","name":"EL INFORMATIVO DE TAMAULIPAS","description":"Desde la Zona Metropolitana Para Todo M\u00e9xico","publisher":{"@id":"https:\/\/elinformativotam.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elinformativotam.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elinformativotam.com\/#organization","name":"EL INFORMATIVO DE TAMAULIPAS","url":"https:\/\/elinformativotam.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elinformativotam.com\/#\/schema\/logo\/image\/","url":"https:\/\/elinformativotam.com\/wp-content\/uploads\/2026\/02\/Cabezal.png","contentUrl":"https:\/\/elinformativotam.com\/wp-content\/uploads\/2026\/02\/Cabezal.png","width":960,"height":640,"caption":"EL INFORMATIVO DE TAMAULIPAS"},"image":{"@id":"https:\/\/elinformativotam.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elinformativotam.com\/#\/schema\/person\/78e08040eed0f6110f0c5f83b6153590","name":"El Informativo Tam","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3b7ad3af540688955925ac610647be00b0cf41feea9c4978b73a707ee86bc53?s=96&d=mm&r=g","caption":"El Informativo Tam"}}]}},"_links":{"self":[{"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/posts\/10101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/comments?post=10101"}],"version-history":[{"count":1,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/posts\/10101\/revisions"}],"predecessor-version":[{"id":10103,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/posts\/10101\/revisions\/10103"}],"wp:attachment":[{"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/media?parent=10101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/categories?post=10101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elinformativotam.com\/index.php\/wp-json\/wp\/v2\/tags?post=10101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}